{"id":3823,"date":"2022-07-06T08:40:00","date_gmt":"2022-07-06T06:40:00","guid":{"rendered":"https:\/\/www.casinobarcelona.es\/blog\/?p=3823"},"modified":"2024-07-22T11:52:59","modified_gmt":"2024-07-22T09:52:59","slug":"review-tragaperras-de-gnomos","status":"publish","type":"post","link":"https:\/\/www.casinobarcelona.es\/blog\/review-tragaperras-de-gnomos\/","title":{"rendered":"Las tragaperras de gnomos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las <a href=\"https:\/\/www.casinobarcelona.es\/slots\/slots-gnomos.html\">tragaperras de gnomos<\/a> bien podr\u00edan encabezar cualquier clasificaci\u00f3n entre las m\u00e1s divertidas del momento. Buena parte de los proveedores m\u00e1s reputados han usado a estos seres en muchas de sus creaciones para dar a los jugadores la experiencia m\u00e1s inmersiva y simp\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los usuarios de Casino Barcelona pueden acceder a distintas tragaperras de gnomos en nuestro men\u00fa de slots. En el buscador de la secci\u00f3n de estos juegos es muy sencillo encontrar esta tem\u00e1tica con toda la fuerza de sus dise\u00f1os y las m\u00e1s variadas funciones. Hoy vamos a darte las claves m\u00e1s destacadas de algunas de las slots m\u00e1s potentes de este tipo. Recuerda que, pese a lo divertido de estas propuestas, est\u00e1s poniendo en juego tu dinero por lo que siempre debes jugar con responsabilidad.<\/p>\n\n\n\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1  uagb-block-d339b8fc      \"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"105\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tTabla de contenidos\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class='uagb-toc__separator'><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#gnomos-mix-sus-caracter\u00edsticas-t\u00e9cnicas-m\u00e1s-destacadas\" class=\"uagb-toc-link__trigger\">Gnomos Mix: sus caracter\u00edsticas t\u00e9cnicas m\u00e1s destacadas<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#funciones-extra-de-gnomos-mix\" class=\"uagb-toc-link__trigger\">Funciones extra de Gnomos Mix<\/a><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#gnomos-respin-todos-los-detalles-de-una-gran-slot\" class=\"uagb-toc-link__trigger\">Gnomos Respin: todos los detalles de una gran slot<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#funciones-extra-de-gnomos-respin\" class=\"uagb-toc-link__trigger\">Funciones extra de Gnomos Respin<\/a><\/li><\/ul><\/li><\/ul><\/li><li class=\"uagb-toc__list\"><a href=\"#conclusiones-sobre-las-tragaperras-online-de-gnomos\" class=\"uagb-toc-link__trigger\">Conclusiones sobre las tragaperras online de gnomos<\/a><ul class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#preguntas-frecuentes\" class=\"uagb-toc-link__trigger\">Preguntas frecuentes<\/a><\/ul><\/ul><\/ul><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\n<h2 class=\"wp-block-heading\" id=\"h-gnomos-mix-sus-caracteristicas-tecnicas-mas-destacadas\">Gnomos Mix: sus caracter\u00edsticas t\u00e9cnicas m\u00e1s destacadas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En nuestra oferta de <a href=\"https:\/\/www.casinobarcelona.es\/slots.html\">slots online<\/a>, la tragaperras Gnomos Mix destaca por muchos motivos. Por supuesto, su personaje principal es un gnomo de colores capaz de arrancarle una sonrisa a cualquiera. Los duendes de la suerte pueden acabar siendo tus mejores aliados en un bosque en el que se esconden grandes tesoros de todo tipo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"711\" src=\"https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-mix-1-1-1024x711.webp\" alt=\"gnomos-mix\" class=\"wp-image-3827\" srcset=\"https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-mix-1-1-1024x711.webp 1024w, https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-mix-1-1-300x208.webp 300w, https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-mix-1-1-768x534.webp 768w, https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-mix-1-1.webp 1104w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En <a href=\"https:\/\/www.casinobarcelona.es\/slots\/gnomos-mix.html\">Gnomos Mix<\/a>, han trabajado codo con codo dos de las empresas m\u00e1s representativas del sector de creaci\u00f3n de juegos en Espa\u00f1a como son MGA y R. Franco. Su propuesta es que vivas un tiempo entre setas para ir a por los premios que proponen en sus 3 carretes y sus 5 divertidos minijuegos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta mec\u00e1nica, Gnomos Mix permite optar a premios m\u00e1ximos de hasta 15.000 euros. Entre sus s\u00edmbolos destacan de manera muy especial las frutas, las hadas, los diamantes o las setas. Todos ellos ofrecen un dise\u00f1o deslumbrante para que cada giro sea lo m\u00e1s inmersivo posible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Funciones extra de Gnomos Mix<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Hay muchas otras cualidades que destacar en esta tragaperras online. Su varianza es media y su RTP oscila entre el 80 y el 95%. Con estas cifras, queda claro que no estamos ante una slot online demasiado potente en cuanto a premios, pero sus posibilidades mejoran notablemente de la mano de sus 5 minijuegos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Calderos:<\/strong> ver\u00e1s aparecer en la pantalla 3 calderos diferentes. Solo tendr\u00e1s que elegir el que prefieras y proceder a descubrir el premio que est\u00e1 en su interior.<\/li>\n\n\n\n<li><strong>Trilero: <\/strong>las cerraduras con las que te encontrar\u00e1s aqu\u00ed esconden recompensas muy interesantes.<\/li>\n\n\n\n<li><strong>Moky: <\/strong>el travieso ser que protagoniza la tragaperras Gnomos Mix esconde monedas de oro de diferentes valores. En este caso, estamos hablando de premios directos para los jugadores.<\/li>\n\n\n\n<li><strong>Fresas: <\/strong>ver\u00e1s aparecer distintos recipientes llenos de fresas. En todos y cada uno de ellos hay premios de valores diversos que tan solo tendr\u00e1s que atreverte a descubrir.<\/li>\n\n\n\n<li><strong>Busca premio: <\/strong>en este caso, son las casas de los gnomos el lugar en el que te esperan los mejores premios de esta alocada tragaperras online.<\/li>\n<\/ul>\n\n\n\n<!-- <div class=\"register-cta register-cta__\">\n    <div class=\"register-cta__banner\" style=\"background-image:url('-bg.webp');\"><\/div>\n    <div class=\"register-cta__content__wrapper\">\n        <div class=\"register-cta__assets\">\n            <div class=\"register-cta__asset1\">\n                <img decoding=\"async\" alt=\"Figura  de CasinoBarcelona\" src=\"-figure.webp\" \/>\n            <\/div>\n            <div class=\"register-cta__asset2\">\n                <img decoding=\"async\" alt=\"Estrellas del Logo de CasinoBarcelona\" src=\"stars.webp\" \/>\n            <\/div>\n        <\/div>\n        <div class=\"register-cta__content\">\n            <div class=\"register-cta__title\">\n                        <\/div>\n            <div class=\"register-cta__button\">\n                <a href=\"\" title=\"\" target=\"_blank\"> <i class=\"fas fa-chevron-circle-right\"><\/i><\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div> -->\n\n<div class=\"register-cta register-cta__slots\">\n    \n    <img decoding=\"async\" src=\"https:\/\/www.casinobarcelona.es\/blog\/wp-content\/themes\/casinobarcelona-blog\/blocks\/register-block\/images\/slots.webp\">\n    \n    <div class=\"register-cta__content__wrapper\">\n        <div class=\"title\">Crea tu Cuenta<\/div>\n        <a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.casinobarcelona.es\/register.html?memberid=4&#038;sourceid=200\" title=\"Crea tu Cuenta\" target=\"_blank\">\u00a1Reg\u00edstrate!<\/a>\n    <\/div>\n\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Gnomos Respin: todos los detalles de una gran slot<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si alguno de los que nos est\u00e9n leyendo piensan en las tragaperras de gnomos como una magn\u00edfica forma de aventuras, <a href=\"https:\/\/www.casinobarcelona.es\/slots\/gnomos-respin.html\">Gnomos Respin<\/a> es el juego ideal. Este inteligente ser te ayudar\u00e1 en todo momento a descubrir las recompensas que pueden estar ocultas en los lugares m\u00e1s insospechados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proveedor espa\u00f1ol R. Franco ha creado esta slot online con una mec\u00e1nica de 5 carretes, 3 o 4 filas y entre 25 y 50 l\u00edneas de pago. Entre sus s\u00edmbolos, destacan las frutas de todo tipo, las campanas y las gemas de colores, pero en la parte superior te esperan tambi\u00e9n flores, \u00e1rboles, hongos y 7 de la suerte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-review-1-1024x576.webp\" alt=\"gnomos-respin-review\" class=\"wp-image-3825\" srcset=\"https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-review-1-1024x576.webp 1024w, https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-review-1-300x169.webp 300w, https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-review-1-768x432.webp 768w, https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-review-1.webp 1209w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Funciones extra de Gnomos Respin<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Desde nuestro <a href=\"https:\/\/www.casinobarcelona.es\/\">casino online<\/a>, queremos contarte c\u00f3mo jugar a las tragaperras de gnomos m\u00e1s potentes. Para sacarles el m\u00e1ximo partido, es vital que conozcas a fondo las funciones extra que ofrecen en cada caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Gnomos Respin, el s\u00edmbolo comod\u00edn es vital en este sentido porque tiene la capacidad de sustituir al resto, excepto al caldero, al wild especial y a todos los de bonificaci\u00f3n. Teniendo en cuenta esto, es bueno que sepas las claves de estas funciones extra:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Caldero de la suerte: <\/strong>cuando veas aparecer este s\u00edmbolo, se te mostrar\u00e1 el multiplicador elegido de una manera totalmente azarosa. Esa cantidad se aplicar\u00e1 al premio que consigas tras una tirada. En esta slot online, puedes hacerte con multiplicadores de 2, 3, 5 o 10 veces el valor de la apuesta que hayas realizado. Adem\u00e1s, si en los re-spins aparece un wild especial, se te conceder\u00e1 un nuevo re-spin.<\/li>\n\n\n\n<li><strong>Bono de la suerte:<\/strong> el acceso a esta funci\u00f3n se lograr\u00e1 de la mano del s\u00edmbolo del gnomo. Ah\u00ed es donde se presentar\u00e1n 3 premios potenciales posibles. Ser\u00e1 al cerrar las tapas cuando podr\u00e1s descubrir la recompensa que te corresponda. En esta funci\u00f3n, el premio m\u00e1s alto que se puede llegar a obtener asciende a 30x.<\/li>\n\n\n\n<li><strong>Bono de hadas:<\/strong> el poblado de estas m\u00e1gicas criaturas alberga todo tipo de premios, as\u00ed que deber\u00e1s adentrarte en \u00e9l para ir conoci\u00e9ndolos poco a poco. Tendr\u00e1s que seleccionar las puertas que quieras para ir acumulando premios. Lo m\u00e1ximo que se puede llegar a obtener son 50x.<\/li>\n\n\n\n<li><strong>Bono calderos:<\/strong> hay 3 tipos distintos de calderos. El usuario puede rechazar los que vaya viendo y elegir el que m\u00e1s le convenga. Pese a esto, en el caso de rechazar los dos primeros, el tercero ser\u00e1 el que otorgue el premio que corresponda. Tambi\u00e9n en este caso, te espera una recompensa m\u00e1xima de 50x.<br><\/li>\n<\/ul>\n\n\n\n<div class=\"banner-block banner-block--welcome-casino\">\n    <a class=\"banner-block__link\" href=\"https:\/\/www.casinobarcelona.es\/promociones\/casino-200.html?memberid=4&#038;sourceid=402\" target=\"_blank\">\n        <img decoding=\"async\" \n            src=\"https:\/\/www.casinobarcelona.es\/blog\/wp-content\/themes\/casinobarcelona-blog\/blocks\/banner-block\/images\/welcome-casino-lg.webp?v=2\"\n            srcset=\"https:\/\/www.casinobarcelona.es\/blog\/wp-content\/themes\/casinobarcelona-blog\/blocks\/banner-block\/images\/welcome-casino-sm.webp?v=2 350w,\n                    https:\/\/www.casinobarcelona.es\/blog\/wp-content\/themes\/casinobarcelona-blog\/blocks\/banner-block\/images\/welcome-casino-md.webp?v=2 720w,\n                    https:\/\/www.casinobarcelona.es\/blog\/wp-content\/themes\/casinobarcelona-blog\/blocks\/banner-block\/images\/welcome-casino-lg.webp?v=2 1000w\"\n            >\n    <\/a>\n\t<a href=\"https:\/\/www.casinobarcelona.es\/promociones\/casino-200.html?memberid=4&#038;sourceid=402\" class=\"banner-block__cta banner-block__cta--welcome-casino\" target=\"_blank\">\n\t\tIr a la promo\t<\/a>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Conclusiones sobre las tragaperras online de gnomos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las tragaperras de gnomos son propuestas muy originales y divertidas y puede que esas sean algunas de las claves que explican el \u00e9xito de este tipo de juego entre los usuarios de Casino Barcelona. La alegr\u00eda y la magia de estos seres han demostrado ser grandes polos de atracci\u00f3n para los jugadores y son muchos los proveedores que los ofrecen en nuestra web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las tragaperras online de gnomos son mucho m\u00e1s que un personaje simp\u00e1tico y un dise\u00f1o interesante. Junto a esto, todas ellas ofrecen tambi\u00e9n un buen n\u00famero de opciones extra en las que se suelen esconder los premios m\u00e1s importantes de cuantos conceden estas tragaperras online. Minijuegos con premios directos, giros extras, re-spins o multiplicadores son algunas de las cualidades con las que las slots de gnomos te ayudar\u00e1n a mejorar tus ganancias potenciales. Sea cual sea la que elijas, las tragaperras de gnomos tienen todo lo que buscas para divertirte y para contar con opciones de ganar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Preguntas frecuentes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1l es la fuerza principal de las tragaperras de gnomos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar el protagonismo del juego a estas criaturas m\u00e1gicas dota a las tragaperras de gnomos de una diversi\u00f3n que es muy apreciada por los usuarios de slots online. A esto se le suma siempre un buen dise\u00f1o para hacerlas a\u00fan m\u00e1s atractivas. Adem\u00e1s, los mejores proveedores de juegos del momento han sido capaces de a\u00f1adirles buenas funciones para que ofrezcan ganancias a\u00fan m\u00e1s altas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las slots de gnomos, \u00bfofrecen premios altos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho de que muchos de los grandes proveedores de juegos apuesten con fuerza por las slots de gnomos hace dif\u00edcil dar un patr\u00f3n en este sentido porque hay un poco de todo. En l\u00edneas generales, s\u00ed podemos decir que no faltan buenas oportunidades de mejorar el juego base de la mano de funciones extra o de minijuegos de todo tipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las slots online de gnomos, \u00bfofrecen funciones extra?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, por supuesto, de hecho, son las opciones de juego con las que se puede optar a las mejores recompensas de cuantas conceden las slots de gnomos. Hay comodines, giros extra, re-spins y muchas otras opciones, pero cada slot ofrece las suyas, de ah\u00ed que debas consultar sus caracter\u00edsticas en las descripciones de juegos que te ofrecemos en Casino Barcelona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfSe puede jugar a las tragaperras de gnomos desde el m\u00f3vil?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, se puede. Tal y como ocurre con toda la oferta de slots online de Casino Barcelona, las tragaperras de gnomos tambi\u00e9n est\u00e1n al alcance de nuestros usuarios desde el dispositivo m\u00f3vil que prefieran usar. Para ello, bastar\u00e1 con que accedas a la secci\u00f3n de slots de la web desde tu m\u00f3vil o Tablet, elijas la slot de gnomos que prefieras y juegues con la m\u00e1xima calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juega siempre con responsabilidad<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las tragaperras de gnomos son muy divertidas y cuentan con todo tipo de opciones de juego. Por este motivo, queremos que disfrutes de ellas de la mejor manera posible, as\u00ed que te recomendamos que sigas los designios de la Direcci\u00f3n General de Ordenaci\u00f3n del Juego (DGOJ) en materia de juego responsable. De este modo, podr\u00e1s divertirte con tu elecci\u00f3n manteni\u00e9ndote siempre bien lejos de riesgos innecesarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las tragaperras de gnomos bien podr\u00edan encabezar cualquier clasificaci\u00f3n entre las m\u00e1s divertidas del momento. Buena parte de los proveedores m\u00e1s reputados han usado a estos seres en muchas de sus creaciones para dar a los jugadores la experiencia m\u00e1s inmersiva y simp\u00e1tica. Los usuarios de Casino Barcelona pueden acceder a distintas tragaperras de gnomos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3824,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-3823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reviews"],"uagb_featured_image_src":{"full":["https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-1.webp",1000,563,false],"thumbnail":["https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-1-150x150.webp",150,150,true],"medium":["https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-1-300x169.webp",300,169,true],"medium_large":["https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-1-768x432.webp",768,432,true],"large":["https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-1.webp",800,450,false],"1536x1536":["https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-1.webp",1000,563,false],"2048x2048":["https:\/\/www.casinobarcelona.es\/blog\/wp-content\/uploads\/2022\/08\/gnomos-respin-1.webp",1000,563,false]},"uagb_author_info":{"display_name":"casino","author_link":"https:\/\/www.casinobarcelona.es\/blog\/author\/casino\/"},"uagb_comment_info":0,"uagb_excerpt":"Las tragaperras de gnomos bien podr\u00edan encabezar cualquier clasificaci\u00f3n entre las m\u00e1s divertidas del momento. Buena parte de los proveedores m\u00e1s reputados han usado a estos seres en muchas de sus creaciones para dar a los jugadores la experiencia m\u00e1s inmersiva y simp\u00e1tica. Los usuarios de Casino Barcelona pueden acceder a distintas tragaperras de gnomos&hellip;","_links":{"self":[{"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/posts\/3823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/comments?post=3823"}],"version-history":[{"count":2,"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/posts\/3823\/revisions"}],"predecessor-version":[{"id":7228,"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/posts\/3823\/revisions\/7228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/media\/3824"}],"wp:attachment":[{"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/media?parent=3823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/categories?post=3823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.casinobarcelona.es\/blog\/wp-json\/wp\/v2\/tags?post=3823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}